{"id":447,"date":"2024-06-05T12:14:00","date_gmt":"2024-06-05T10:14:00","guid":{"rendered":"http:\/\/inprincipo2024.inprincipo.com\/?p=447"},"modified":"2024-10-21T10:50:39","modified_gmt":"2024-10-21T08:50:39","slug":"in-principo-partenaire-de-terres-de-chercheurs","status":"publish","type":"post","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2024\/06\/05\/in-principo-partenaire-de-terres-de-chercheurs\/","title":{"rendered":"In Principo partenaire de \u00ab\u00a0Terres de Chercheurs\u00a0\u00bb"},"content":{"rendered":"\n<p><strong><em>In Principo poursuit son d\u00e9veloppement dans les Hauts-de-France en accompagnant, avec InSitoo Conseil, l\u2019Institut Pasteur de Lille sur ses \u00e9volutions internes et sur sa campagne \u201cTerres de Chercheurs\u201d destin\u00e9e \u00e0 lever 15 millions d\u2019euros de dons afin de renforcer sa dynamique d\u2019\u00e9cosyst\u00e8me de recherche fondamentale unique en Europe.<\/em><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi l\u2019Institut Pasteur de Lille est important&nbsp;?<\/h2>\n\n\n\n<p>Fond\u00e9 par Louis Pasteur il y a 130 ans, l\u2019Institut Pasteur de Lille est une institution scientifique connue pour ses recherches, ses d\u00e9couvertes (\u00e0 commencer par le BCG),&nbsp;<strong>son excellence et l\u2019autonomie accord\u00e9e aux chercheurs sur un Campus dot\u00e9 de moyens uniques.&nbsp;<\/strong>L\u2019Institut Pasteur de Lille est, en revanche, moins connu pour son fonctionnement sp\u00e9cifique. C\u2019est une&nbsp;<strong>fondation priv\u00e9e<\/strong>&nbsp;financi\u00e8rement et juridiquement ind\u00e9pendante,&nbsp;<strong>dont les activit\u00e9s de recherche sont financ\u00e9es \u00e0 75% par sa capacit\u00e9 \u00e0 lever des fonds<\/strong>. Ainsi, chaque ann\u00e9e, l\u2019Institut finance son budget scientifique de 20&nbsp;M\u20ac par 6&nbsp;M\u20ac de subvention et 15&nbsp;M\u20ac de lev\u00e9e de fonds dont 9&nbsp;M\u20ac de dons et 5&nbsp;M\u20ac d\u2019appel \u00e0 projets<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un \u00e9cosyst\u00e8me de recherche fondamentale unique<\/h2>\n\n\n\n<p>Aujourd\u2019hui, l\u2019Institut Pasteur de Lille associe sur son Campus 34 \u00e9quipes de recherche en 7 grandes unit\u00e9s int\u00e8grant des acteurs de la recherche publique (INSERM, CNRS), diff\u00e9rentes \u00e9quipes universitaires, le Centre Hospitalier Universitaire de Lille, et des entreprises travaillant sur des recherches en sant\u00e9. Plus de 800 personnes travaillent sur le Campus Pasteur.&nbsp;<strong>L\u2019Institut Pasteur de Lille est le seul \u00e9cosyst\u00e8me de recherche en sant\u00e9&nbsp;<\/strong>capable d\u2019aller de la recherche fondamentale \u00e0 la recherche clinique, d\u2019int\u00e9grer une relation au patient, d\u2019aller jusqu\u2019\u00e0 la cr\u00e9ation de valeur \u00e9conomique et m\u00eame \u00e0 la cr\u00e9ation de startups telle GENFIT, n\u00e9e sur le Campus il y a vingt-cinq ans.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une lev\u00e9e de fonds de 15&nbsp;M\u20ac suppl\u00e9mentaires<\/h2>\n\n\n\n<p><strong>Cette ann\u00e9e, l\u2019Institut Pasteur de Lille entreprend de lever 15&nbsp;M\u20ac suppl\u00e9mentaires pour les 5 prochaines ann\u00e9es afin de s\u00e9curiser sa croissance scientifique&nbsp;: intensification de ses programmes de recherche, mont\u00e9e des co\u00fbts des recherches, besoin de s\u00e9curisation financi\u00e8re de l\u2019Institut.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-IPL-la-recherche-a-un-cout.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-1268\" srcset=\"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-IPL-la-recherche-a-un-cout.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-IPL-la-recherche-a-un-cout.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-IPL-la-recherche-a-un-cout.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Un enjeu critique de sant\u00e9 et de souverainet\u00e9<\/h2>\n\n\n\n<p>Toutes les \u00e9tudes prospectives nous l\u2019indiquent (<a href=\"https:\/\/www.leem.org\/publication\/sante-2030-une-analyse-prospective-de-linnovation-en-sante\">Voir Etude Sant\u00e9 2030 du LEEM<\/a>), la sant\u00e9 va reprendre une part majeure de notre avenir europ\u00e9en. Fait majeur, l\u2019esp\u00e9rance de vie continue d\u2019augmenter. Un enfant sur deux n\u00e9 apr\u00e8s 2000 va vivre centenaire avec une esp\u00e9rance de vie en bonne sant\u00e9 de plus de dix ans apr\u00e8s 65 ans, les maladies infectieuses renforcent leur menaces, l\u2019antibio-r\u00e9sistance se renforce, des maladies oubli\u00e9es reviennent&nbsp;: tuberculose, coqueluche, notamment.&nbsp;<strong>Le changement climatique enfin, va bouleverser les \u00e9cosyst\u00e8mes de nos pays et exposer nos populations \u00e0 des risques in\u00e9dits. La sant\u00e9 va \u00eatre un d\u00e9terminant de notre avenir fran\u00e7ais et europ\u00e9en.<\/strong><br>Il suffit que quelques dizaines d\u2019entreprises fran\u00e7aises et grands donateurs, conscients de ces enjeux de sant\u00e9, investis dans une responsabilit\u00e9 sociale, pr\u00e9occup\u00e9s par les questions de souverainet\u00e9, r\u00e9pondent, \u00e0 hauteur de quelques centaines de milliers d\u2019euros, \u00e0 la campagne Terres de Chercheurs pour significativement changer la donne, avoir un impact consid\u00e9rable, durable.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"115\" src=\"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-logo_terres-de-chercheurs.png?resize=200%2C115&#038;ssl=1\" alt=\"\" class=\"wp-image-1269\"\/><\/figure>\n\n\n\n<p>L\u2019Institut Pasteur de Lille a intitul\u00e9 sa campagne de lev\u00e9e de dons Terres de Chercheurs en hommage \u00e0 l\u2019appellation des Hauts de France qui se proclame \u00ab&nbsp;Terres d\u2019Entrepreneurs&nbsp;\u00bb. Pour \u00eatre durablement une \u00ab&nbsp;Terre d\u2019Entrepreneurs&nbsp;\u00bb en sant\u00e9, il faut avant tout \u00eatre une \u00ab&nbsp;Terres de Chercheurs&nbsp;\u00bb nous rappelle l\u2019Institut.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Et pourquoi, c\u2019est important pour In Principo&nbsp;?<\/h2>\n\n\n\n<p><strong>L\u2019\u00e9cosyst\u00e8me de recherche fondamentale Pasteur de Lille est \u00e0 un tournant de son \u00e9volution scientifique en termes d\u2019engagement de moyens pour poursuivre ses activit\u00e9s et d\u00e9livrer davantage de r\u00e9sultats qui s\u2019annoncent majeurs<\/strong>&nbsp;sur la sant\u00e9, le vieillissement, Alzheimer, diab\u00e8te, antibior\u00e9sistance, et des impacts sur l\u2019\u00e9cosyst\u00e8me de la sant\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-pipette-pasteur-prelevement-biologique.jpg?resize=1000%2C666&#038;ssl=1\" alt=\"\" class=\"wp-image-1270\" srcset=\"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-pipette-pasteur-prelevement-biologique.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-pipette-pasteur-prelevement-biologique.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-pipette-pasteur-prelevement-biologique.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Un \u00e9cosyst\u00e8me de recherche fondamentale d\u00e9termine la pr\u00e9sence et la collaboration de chercheurs, une cascade de programmes de recherche qui sont localis\u00e9s en France, la pr\u00e9sence active d\u2019acteurs industriels du m\u00e9dicament en France, de la recherche op\u00e9rationnelle \u00e0 la production de m\u00e9dicament sur notre sol. Et nous l\u2019avons vu avec la crise sanitaire, disposer de ces industries de sant\u00e9 en France, c\u2019est critique, c\u2019est strat\u00e9gique.<\/p>\n\n\n\n<p><strong>L\u2019Institut Pasteur de Lille constitue donc non seulement un enjeu de recherche en sant\u00e9 mais plus encore un c\u0153ur d\u2019enjeu de souverainet\u00e9 nationale, europ\u00e9enne, le coeur d\u2019une dynamique, un enjeu strat\u00e9gique.<br><\/strong><br><strong>Pour In Principo, nous sommes entr\u00e9s dans une soci\u00e9t\u00e9 d\u2019\u00e9cosyst\u00e8mes, une transformation de la soci\u00e9t\u00e9 par les \u00e9cosyst\u00e8mes.<\/strong>&nbsp;Plus encore que nos industries &#8211; dont on sait aujourd\u2019hui \u00e0 quel point elles sont strat\u00e9giques et d\u00e9terminantes &#8211; c\u2019est la pr\u00e9sence active d\u2019\u00e9cosyst\u00e8mes puissants sur notre sol qui d\u00e9termine notre avenir.&nbsp;<strong>Et l\u2019Institut Pasteur de Lille est au coeur d\u2019un des plus puissants \u00e9cosyst\u00e8mes de sant\u00e9 en Europe.<\/strong>&nbsp;C\u2019est un enjeu de souverainet\u00e9, c\u2019est un enjeu d\u2019avenir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour aller plus loin dans la mobilisation<\/h2>\n\n\n\n<p>La plupart d\u2019entre nous sommes profanes de ces questions complexes qui, ont l\u2019a vu il y a peu, peuvent bouleverser nos vies collectives, et continueront pour les temps \u00e0 venir d\u2019impacter nos vies personnelles. Avec l\u2019Institut Pasteur de Lille, In Principo d\u00e9veloppe&nbsp;<strong>des actions de sensibilisation collaboratives, des conf\u00e9rences<\/strong>, des formats pour impliquer, monter en conscience, nous connecter collectivement davantage aux d\u00e9fis de la sant\u00e9, aux enjeux de la sant\u00e9 du futur, aux plans individuel, collectif, social, soci\u00e9tal et strat\u00e9gique. Ces d\u00e9marches s\u2019int\u00e8grent dans l<strong>es programmes dits de contrepartie pour les entreprises<\/strong>s\u2019engageant aupr\u00e8s de l\u2019Institut Pasteur de Lille dans le cadre de \u00ab&nbsp;Terres de Chercheurs&nbsp;\u00bb.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline has-poppins-font-family is-style-outline--1\" style=\"font-style:normal;font-weight:400\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"http:\/\/inprincipo2024.inprincipo.com\/index.php\/contact\/\" style=\"background-color:#ffffff24\">CONTACTEZ-NOUS !<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In Principo poursuit son d\u00e9veloppement dans les Hauts-de-France en accompagnant, avec InSitoo Conseil, l\u2019Institut Pasteur de Lille sur ses \u00e9volutions internes et sur sa campagne \u201cTerres de Chercheurs\u201d destin\u00e9e \u00e0 lever 15 millions d\u2019euros de dons afin de renforcer sa dynamique d\u2019\u00e9cosyst\u00e8me de recherche fondamentale unique en Europe. Pourquoi l\u2019Institut Pasteur de Lille est important&nbsp;? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/06\/INP-Terre-de-chercheurs-affiche-600x600-1.jpg?fit=600%2C600&ssl=1","jetpack-related-posts":[{"id":1365,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2024\/01\/22\/parlons-formation-les-31-janvier-et-8-fevrier-2024\/","url_meta":{"origin":447,"position":0},"title":"Parlons Formation les 31 janvier et 8 f\u00e9vrier 2024","author":"In Principo","date":"22 janvier 2024","format":false,"excerpt":"Le Catalogue l\u2019Institut des Dynamiques Collaboratives 2024-2025 est paru \u2026 parlons-en\u00a0!Vous pouvez d\u00e9sormais activer votre transformation manag\u00e9riale vers les Dynamiques R\u00e9g\u00e9n\u00e9rActives avec 4 programmes et 4 parcours pleinement op\u00e9rationnels avec l\u2019Institut des Dynamiques Collaboratives by In Principo. R\u00e9pondre \u00e0 vos questions\u00a0! Comment s\u2019y prendre\u00a0? Sur \u00e9tag\u00e8re ou offre configur\u00e9e sur\u2026","rel":"","context":"Dans &quot;FORMATIONS&quot;","block_context":{"text":"FORMATIONS","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/formations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-Couv-catalogue-formations-600x600-1.jpg?fit=600%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-Couv-catalogue-formations-600x600-1.jpg?fit=600%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/10\/INP-Couv-catalogue-formations-600x600-1.jpg?fit=600%2C600&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":7651,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2026\/03\/01\/olivier-reaud-invite-de-first-in-the-future-mardi-3-mars-2026-de-8h30-a-12h00-le-club-dirigeants-de-ifrn\/","url_meta":{"origin":447,"position":1},"title":"Olivier R\u00e9aud, invit\u00e9 de \u00ab\u00a0First In The Future\u00a0\u00bb, Mardi 3 mars 2026 de 8H30 \u00e0 12H00, le Club Dirigeants de IFRN","author":"Olivier Reaud","date":"1 mars 2026","format":false,"excerpt":"Mardi 3 mars, c\u2019est \u00e0 une double invitation que Olivier R\u00e9aud r\u00e9pond. Olivier sera l\u2019invit\u00e9 principal de la session \u00ab First In The Future \u00bb sur l\u2019\u00e9volution de la nature du leadership dans les organisations d\u2019aujourd\u2019hui et en m\u00eame temps l\u2019h\u00f4te de la session elle-m\u00eame, car IFRN est accueillie par\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/03\/Cartouche-INP-Olivier-Reaud-First-In-The-Future-3-mars-V2.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/03\/Cartouche-INP-Olivier-Reaud-First-In-The-Future-3-mars-V2.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/03\/Cartouche-INP-Olivier-Reaud-First-In-The-Future-3-mars-V2.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/03\/Cartouche-INP-Olivier-Reaud-First-In-The-Future-3-mars-V2.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/03\/Cartouche-INP-Olivier-Reaud-First-In-The-Future-3-mars-V2.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7386,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2025\/11\/25\/retour-sur-agrotech-2032-presentation-dun-ecosysteme-de-leconomie-regenerative-a-vocation-preindustrielle\/","url_meta":{"origin":447,"position":2},"title":"Retour sur Agrotech 2032\u00a0: pr\u00e9sentation d\u2019un \u00e9cosyst\u00e8me de l\u2019\u00e9conomie r\u00e9g\u00e9n\u00e9rative \u00e0 vocation pr\u00e9industrielle","author":"In Principo","date":"25 novembre 2025","format":false,"excerpt":"Agrotech. est d\u00e8s sa naissance en 2018, entre Lille et Belgique, entre terres agricoles et friches industrielles textiles, un pari sur la r\u00e9g\u00e9n\u00e9ration d\u2019un territoire. Mardi dernier, 18 novembre, l\u2019\u00e9quipe Agrotech pr\u00e9sentait \u00e0 ses parties prenantes Agrotech 2032, son projet pour aller plus loin, passer d\u2019incubateur tech \u00e0 \u00e9cosyst\u00e8me d\u2019innovation\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/11\/251125-RetourAgrotech2032-Cartouche.png?fit=985%2C985&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/11\/251125-RetourAgrotech2032-Cartouche.png?fit=985%2C985&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/11\/251125-RetourAgrotech2032-Cartouche.png?fit=985%2C985&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/11\/251125-RetourAgrotech2032-Cartouche.png?fit=985%2C985&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6877,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2025\/10\/10\/avec-agrotech-2032-agrotech-willems-entreprend-de-devenir-un-ecosysteme-de-leconomie-regenerative\/","url_meta":{"origin":447,"position":3},"title":"Agrotech Willems entreprend, avec In Principo, de devenir un \u00e9cosyst\u00e8me de l&rsquo;\u00e9conomie r\u00e9g\u00e9n\u00e9rative \u00e0 vocation pr\u00e9industrielle","author":"In Principo","date":"10 octobre 2025","format":false,"excerpt":"Depuis 2018, l'incubateur Agrotech Willems, en partenariat avec EuraTechnologies a d\u00e9j\u00e0 accompagn\u00e9 le d\u00e9veloppement de pr\u00e8s d'une centaine de startups dans les domaines de l'Agriculture et de l'\u00c9conomie Verte. Fort de ce succ\u00e8s, Agrotech Willems ambitionne de devenir \u00e0 l'horizon 2032 un \u00e9cosyst\u00e8me territorial pr\u00e9industriel pionnier de l'\u00e9conomie r\u00e9g\u00e9n\u00e9rative, c\u2019est\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/Agrotech-2032-CarreV5.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/Agrotech-2032-CarreV5.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/Agrotech-2032-CarreV5.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/Agrotech-2032-CarreV5.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/Agrotech-2032-CarreV5.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3554,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2025\/04\/10\/16-avril-olivier-reaud-intervient-au-off-de-iaf-france-sur-le-role-de-la-facilitation-dans-un-monde-imprevisible\/","url_meta":{"origin":447,"position":4},"title":"Olivier R\u00e9aud intervient au OFF de IAF France :   \u00ab\u00a0Le r\u00f4le de la Facilitation dans un Monde Impr\u00e9visible\u00a0\u00bb","author":"In Principo","date":"10 avril 2025","format":false,"excerpt":"IAF France, l\u2019association professionnelle des Facilitateurs en France, organise chaque semaine des \u00e9v\u00e8nements en ligne pour partager les avanc\u00e9es de la facilitation \u00e0 destination des facilitateurs et de leurs destinataires. Mercredi 14 avril, IAF France propose un OFF (pour Open France Facilitation) sur Le R\u00f4le de la Facilitation dans un\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/04\/Cartouche-IAF-OFF-Facilitation-en-imprevisible-CartoucheV2.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/04\/Cartouche-IAF-OFF-Facilitation-en-imprevisible-CartoucheV2.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/04\/Cartouche-IAF-OFF-Facilitation-en-imprevisible-CartoucheV2.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/04\/Cartouche-IAF-OFF-Facilitation-en-imprevisible-CartoucheV2.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/04\/Cartouche-IAF-OFF-Facilitation-en-imprevisible-CartoucheV2.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6935,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2025\/10\/16\/johan-aubert-ceo-de-hair-tech-pro-invite-du-2e-rendez-vous-puissance-dagir\/","url_meta":{"origin":447,"position":5},"title":"Johan Aubert, CEO de HairTechPro, invit\u00e9 du 2e \u00ab\u00a0Rendez-Vous Puissance d\u2019Agir\u00a0\u00bb","author":"In Principo","date":"16 octobre 2025","format":false,"excerpt":"\u00ab\u00a0Adoption de l\u2019IA : au service des enjeux m\u00e9tiers et humains \u00bbMercredi 29 octobre 18H - 19H Si l\u2019IA est si formidable en termes de cr\u00e9ation de valeur, pourquoi ne se traduit-elle que dans l\u2019usage d\u2019applications individuelles ou dans des m\u00e9gaprojets d\u2019entreprise\u00a0? De nombreuses enqu\u00eates le d\u00e9montre\u00a0: la v\u00e9ritable valeur\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251015-Cartouche-PuissanceAgir2-News-Johan_Aubert-CarreV5.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251015-Cartouche-PuissanceAgir2-News-Johan_Aubert-CarreV5.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251015-Cartouche-PuissanceAgir2-News-Johan_Aubert-CarreV5.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251015-Cartouche-PuissanceAgir2-News-Johan_Aubert-CarreV5.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251015-Cartouche-PuissanceAgir2-News-Johan_Aubert-CarreV5.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/comments?post=447"}],"version-history":[{"count":3,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts\/447\/revisions"}],"predecessor-version":[{"id":1272,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts\/447\/revisions\/1272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/media?parent=447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/categories?post=447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/tags?post=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}