{"id":1372,"date":"2024-01-12T19:19:00","date_gmt":"2024-01-12T18:19:00","guid":{"rendered":"https:\/\/inprincipo2024.inprincipo.com\/?p=1372"},"modified":"2025-04-10T13:53:03","modified_gmt":"2025-04-10T11:53:03","slug":"pourquoi-et-comment-transformer-son-organisation-par-la-facilitation","status":"publish","type":"post","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2024\/01\/12\/pourquoi-et-comment-transformer-son-organisation-par-la-facilitation\/","title":{"rendered":"Pourquoi et comment transformer son organisation par la facilitation\u00a0?"},"content":{"rendered":"\n<p><em>Olivier R\u00e9aud anime avec Jacques Fuchs ce mercredi 17 janvier \u00e0 18H00 le OFF de France Facilitation by IAF France \u201cLa puissance de la Facilitation de Transformation\u201d, un atelier en ligne ouvert pour partager sur les enjeux cl\u00e9s de la facilitation.<br>Nous relayons ici l\u2019article Rebonds paru sur le site FranceFacilitation.org qui pr\u00e9pare ce rendez-vous.<\/em><\/p>\n\n\n\n<p><strong><em>De l\u2019acc\u00e9l\u00e9ration digitale \u00e0 la complexit\u00e9 de la transition, d\u2019un monde VUCA \u00e0 la succession ininterrompue de crises depuis cinq ans, les organisations ont appris la n\u00e9cessit\u00e9 de s\u2019adapter, et m\u00eame de se transformer. Et c\u2019est ce mot qui nous questionne.&nbsp;<\/em><\/strong><\/p>\n\n\n\n<p>Car il y a diff\u00e9rentes mani\u00e8res de se transformer, et les mani\u00e8res d\u2019hier qui marchaient d\u00e9j\u00e0 tr\u00e8s mal \u2013 nous vous dirons plus loin pourquoi \u2013 sont aujourd\u2019hui r\u00e9solument contre-productives. Au point que beaucoup de transformations sont mal v\u00e9cues, contre-performantes et d\u00e9sengageantes, au point que beaucoup d\u2019organisations y renoncent, choisissent \u00ab&nbsp;de ne pas se transformer dans un monde qui change&nbsp;!&nbsp;\u00bb. Et c\u2019est un v\u00e9ritable probl\u00e8me tant pour la transition que pour chacune de nos entreprises.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Changer d\u00e9j\u00e0, pourrait \u00eatre simple.<\/h2>\n\n\n\n<p>Changer, c\u2019est remplacer la mani\u00e8re de faire A par la mani\u00e8re B. Se transformer c\u2019est, individuellement et collectivement, \u00e9voluer sur ses pratiques, sa culture, sa conscience, son identit\u00e9, ses repr\u00e9sentations, sa dynamique, son management, ses relations avec ses parties prenantes, sa gouvernance, ses indicateurs, sa performance, sa confiance\u2026 C\u2019est passer de chenille \u00e0 papillon, et m\u00eame continuer \u00e0 \u00e9voluer encore&nbsp;!&nbsp;<\/p>\n\n\n\n<p><strong>Changer c\u2019est simple quand le changement est une opportunit\u00e9<\/strong>. Quand je propose \u00e0 mes enfants d\u2019aller le week-end prochain dans un parc d\u2019attraction c\u00e9l\u00e8bre, je n\u2019ai pas besoin de conduire le changement. C\u2019est une opportunit\u00e9 pour eux, ils sont motiv\u00e9s&nbsp;; abandonner leurs activit\u00e9s habituelles est facilement surmont\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourtant, changer n\u2019est plus si simple\u2026<\/h2>\n\n\n\n<p>Et c\u2019est parce que les \u00ab&nbsp;cabinets de conseil&nbsp;\u00bb sont pass\u00e9s par l\u00e0 avec des th\u00e9ories plus ou moins mortif\u00e8res\u2026&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le changement \u00ab&nbsp;glaciaire&nbsp;\u00bb<\/h3>\n\n\n\n<p>On d\u00e9g\u00e8le, on bouge, on freeze. Efficace mais glacial au plan de l\u2019engagement, du management, de la performance collective, de la capacit\u00e9 d\u2019\u00e9volution.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le changement par \u00ab&nbsp;la courbe du deuil&nbsp;\u00bb<\/h3>\n\n\n\n<p>C\u2019est de loin la pire des approches et \u2013 qui plus est \u2013 la plus pratiqu\u00e9e. Elle pr\u00e9suppose \u00ab&nbsp;la r\u00e9sistance au changement des parties prenantes&nbsp;\u00bb. Elle vise, pour vaincre cette r\u00e9sistance collective suppos\u00e9e, \u00e0 cr\u00e9er les conditions d\u2019une d\u00e9pression psychologique collective \u2013 appel\u00e9e dans le texte \u00ab&nbsp;la vall\u00e9e du d\u00e9sespoir&nbsp;\u00bb \u2013 pour en venir \u00e0 bout par diff\u00e9rents stratag\u00e8mes (tapez changement + vall\u00e9e du d\u00e9sespoir sur votre moteur de recherche, et vous verrez).<br>Cette th\u00e9orie du changement est bas\u00e9e sur de r\u00e9els travaux scientifiques issus d\u2019un tout autre contexte. Dans les ann\u00e9es 70, la psychiatre et psychologue \u00c9lisabeth K\u00fcbler-Ross observe certaines similitudes de comportement face \u00e0 la mort chez les patients (d\u00e9ni, choc, col\u00e8re\u2026) et leurs proches. Elle publie un livre en 1975 \u00ab&nbsp;On Death And Dying&nbsp;\u00bb qui d\u00e9finit 5 \u00e9tapes du processus de deuil. Et dans ce contexte tr\u00e8s particulier, cette m\u00e9thode a du sens.<br>Dans les ann\u00e9es 90, de grands cabinets conseils confront\u00e9s \u00e0 la n\u00e9cessit\u00e9 d\u2019appuyer des d\u00e9marches de r\u00e9-engineering aux forceps, adaptent la m\u00e9thode K\u00fcbler-Ross \u00e0 la conduite du changement. C\u2019est magique&nbsp;: plus on force les collaborateurs \u00e0 changer contre leur gr\u00e9 plus on a des r\u00e9sistances, et plus on a des explications psycho-scientifiques pour les stigmatiser&nbsp;: d\u00e9ni, col\u00e8re, d\u00e9pression, acceptation, s\u00e9r\u00e9nit\u00e9. Dans les ann\u00e9es 2000, la g\u00e9n\u00e9ralisation de ces m\u00e9thodes entrainera des vagues de suicides dans certaines entreprises. Aujourd\u2019hui encore, des cabinets peu scrupuleux ont recours \u00e0 ces m\u00e9thodes pour accompagner la transition\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le changement par l\u2019urgence<\/h3>\n\n\n\n<p>John Paul KOTTER de la Harvard Business School, d\u00e9finit 8 \u00e9tapes de conduite du changement&nbsp;:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cr\u00e9er un sentiment d\u2019urgence.<\/li>\n\n\n\n<li>Cr\u00e9er une coalition.<\/li>\n\n\n\n<li>D\u00e9velopper une vision et une strat\u00e9gie.<\/li>\n\n\n\n<li>Communiquer la vision du changement.<\/li>\n\n\n\n<li>Responsabiliser les collaborateurs.<\/li>\n\n\n\n<li>G\u00e9n\u00e9rer rapidement des r\u00e9sultats.<\/li>\n\n\n\n<li>Consolider le succ\u00e8s.<\/li>\n\n\n\n<li>Ancrer les nouvelles pratiques.<\/li>\n<\/ol>\n\n\n\n<p>C\u2019est efficace pour passer d\u2019un \u00e9tat A stable \u00e0 une \u00e9tat B stable mais cela suppose une approche tr\u00e8s directive, impose une mani\u00e8re de faire, des processus et des pratiques norm\u00e9es, ne d\u00e9veloppe pas d\u2019engagement une fois l\u2019urgence termin\u00e9e et amoindrit fortement la culture d\u2019entreprise. Elle r\u00e9duit au minimum sa capacit\u00e9 collaborative car cette approche va elle aussi \u00e0 l\u2019encontre du collectif. De plus, le changement ne se fait que sur les comportements.<\/p>\n\n\n\n<p>Nous nous arr\u00eaterons \u00e0 ces trois m\u00e9thodes qui ne sont aucunement des m\u00e9thodes de facilitation.&nbsp;<strong>Pourquoi&nbsp;? Parce qu\u2019elles ne rendent pas le collectif acteur de sa transformation.<\/strong>&nbsp;Si la facilitation est connue pour cr\u00e9er les conditions de l\u2019intelligence collective pour d\u00e9passer un enjeu, faire \u00e9voluer un processus, engager une \u00e9volution, elle l\u2019est plus encore pour r\u00e9ussir une transformation.&nbsp;<strong>Car la facilitation de transformation d\u00e9veloppe une puissance d\u2019engagement au sein du collectif qui lui permet de se transformer par lui-m\u00eame, durablement, avec sa propre \u00e9nergie&nbsp;!&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reprenons au point de d\u00e9part<\/h2>\n\n\n\n<p><strong>S\u2019il y a un besoin de transformation, c\u2019est qu\u2019il y a une opportunit\u00e9 \u00e0 se transformer&nbsp;:&nbsp;<\/strong>\u00ab&nbsp;Demain notre activit\u00e9 sera obsol\u00e8te&nbsp;\u00bb, \u00ab&nbsp;nous ferons face \u00e0 une forte concurrence&nbsp;\u00bb, \u00ab&nbsp;nous avons l\u2019opportunit\u00e9 de d\u00e9velopper de nouveaux services&nbsp;\u00bb, \u00ab&nbsp;de mieux satisfaire ses clients&nbsp;\u00bb, \u00ab&nbsp;d\u2019apporter de nouveaux bienfaits \u00e0 la soci\u00e9t\u00e9 et \u00eatre r\u00e9compens\u00e9e par une hausse de ses revenus \u00e0 long terme&nbsp;\u00bb, \u00ab&nbsp;notre organisation sera plus agile, plus innovante, plus efficiente et d\u00e9veloppera un meilleur impact \u00bb\u2026&nbsp;<\/p>\n\n\n\n<p>La premi\u00e8re \u00e9tape est donc de cr\u00e9er les conditions au sein du collectif de s\u2019approprier ces enjeux, de&nbsp;<strong>\u00ab&nbsp;mettre le collectif en situation d\u2019opportunit\u00e9&nbsp;\u00bb<\/strong>. La vision de l\u2019opportunit\u00e9 de transformation engendre l\u2019\u00e9nergie de l\u2019action transformatrice&nbsp;: envie collective de devenir, ambition collective de se transformer, d\u00e9termination \u00e0 y parvenir.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La transformation par la facilitation travaille avec le Collectif<\/h2>\n\n\n\n<p>Elle lui permet de prendre conscience des enjeux internes et externes, de d\u00e9velopper sa conscience de lui-m\u00eame, l\u2019engage \u00e0 explorer, \u00e0 exp\u00e9rimenter, \u00e0 se questionner, \u00e0 apprendre par it\u00e9ration, \u00e0 aller au bout de sa transformation puis \u00e0 s\u2019inscrire dans une \u00e9volution continue.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La force d\u2019une transformation par la facilitation se caract\u00e9rise par 5&nbsp;b\u00e9n\u00e9fices&nbsp;:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ces transformations sont puissantes et enthousiastes car elles sont port\u00e9es par un collectif moteur, avec une forte \u00e9nergie positive\u00a0;<\/li>\n\n\n\n<li>Ces transformations sont cr\u00e9atives et cr\u00e9atrices de valeur et d\u2019impact car elles mobilisent les participants sur leur m\u00e9tier, leur client, les invite \u00e0 agir de mani\u00e8re cr\u00e9ative sur leurs propres d\u00e9fis\u00a0;<\/li>\n\n\n\n<li>Ces transformations sont transformantes au plan culturel par plusieurs cycles de prises de conscience, d\u2019exp\u00e9riences collectives, de partages r\u00e9flexifs, augmentant \u00e0 chaque it\u00e9ration la port\u00e9e de la transformation et mobilisant progressivement des valeurs nouvelles soutenue par l\u2019\u00e9nergie collective\u00a0;<\/li>\n\n\n\n<li>Ces transformations impactent le mode de fonctionnement interne et externe de l\u2019organisation, ses capacit\u00e9s collaboratives, l\u2019engagement, la performance et la confiance du collectif en lui-m\u00eame\u00a0;<\/li>\n\n\n\n<li>Ces transformations engendrent plus encore des dynamiques auto-\u00e9volutives qui s\u2019inscrivent dans le temps\u00a0: l\u2019\u00e9nergie de poursuivre une transformation continue pour devenir un v\u00e9ritable diff\u00e9renciateur strat\u00e9gique.<\/li>\n<\/ul>\n\n\n\n<p><strong>Dans les transformations port\u00e9es de bout en bout par la facilitation, l\u2019intelligence collective devient continue.&nbsp;<\/strong>Dans les approches m\u00e9canistes, l\u2019organisation comme structure nouvelle est peut-\u00eatre l\u00e0 mais le collectif comme puissance vivante et engageante est \u00e9teint.&nbsp;<strong>L\u2019une continuera d\u2019\u00e9voluer, d\u2019anticiper, d\u2019innover, d\u2019am\u00e9liorer sa valeur et son impact. L\u2019autre restera fig\u00e9e dans son \u00e9tat \u00ab&nbsp;B&nbsp;\u00bb.<br><\/strong><br><strong>Dans un monde en perp\u00e9tuelle \u00e9volution, la diff\u00e9rence est flagrante.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>De cette conscience et de cette \u00e9nergie se d\u00e9veloppent aujourd\u2019hui plusieurs approches de la transformation par la facilitation que nous vous exposerons le 17 janvier&nbsp;: transformation par les dynamiques collaboratives, facilitation syst\u00e9mique, transformation r\u00e9g\u00e9n\u00e9rActive. Nous invitons ici les praticiens d\u2019approches de transformation par la facilitation \u00e0 proposer leurs approches pour un partage entre pairs.<br><\/strong><br><strong>Le site France Facilitation by IAF&nbsp;:<\/strong>&nbsp;<a href=\"https:\/\/francefacilitation.org\/\">francefacilitation.org<\/a><\/p>\n\n\n\n<p><strong>L\u2019article sur le site France Facilitation&nbsp;:<\/strong>&nbsp;<a href=\"https:\/\/francefacilitation.org\/2024\/01\/11\/pourquoi-et-comment-transformer-son-organisation-par-la-facilitation\/\">francefacilitation.org<\/a><\/p>\n\n\n\n<p><strong>S\u2019inscrire en ligne au OFF de mercredi 17 janvier&nbsp;:<\/strong>&nbsp;<a href=\"https:\/\/iaf-france.assoconnect.com\/collect\/description\/384557-u-la-puissance-de-la-facilitation-de-transformation-off-17-01-24\">S\u2019inscrire sur IAF France<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olivier R\u00e9aud anime avec Jacques Fuchs ce mercredi 17 janvier \u00e0 18H00 le OFF de France Facilitation by IAF France \u201cLa puissance de la Facilitation de Transformation\u201d, un atelier en ligne ouvert pour partager sur les enjeux cl\u00e9s de la facilitation.Nous relayons ici l\u2019article Rebonds paru sur le site FranceFacilitation.org qui pr\u00e9pare ce rendez-vous. De [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-1372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/01\/240112-CartoucheBlogV2.png?fit=1022%2C1022&ssl=1","jetpack-related-posts":[{"id":1324,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2024\/03\/15\/olivier-reaud-intervient-a-linterlab-iaf-france-la-facilitation-de-transformation-quelle-difference\/","url_meta":{"origin":1372,"position":0},"title":"Olivier R\u00e9aud intervient \u00e0 l\u2019Interlab IAF France\u00a0: \u201cLa Facilitation de Transformation, quelle diff\u00e9rence\u00a0?\u201d","author":"In Principo","date":"15 mars 2024","format":false,"excerpt":"Vendredi 22 mars, Olivier R\u00e9aud et Jacques Fuchs animent un Interlab (un atelier France Facilitation by IAF r\u00e9serv\u00e9 aux abonn\u00e9s), sur la \u00ab\u00a0Facilitation de Transformation\u00a0\u00bb, propos\u00e9 dans la suite du OFF du 17 janvier sur le m\u00eame th\u00e8me. Pour les deux intervenants, la \u00ab\u00a0Facilitation de Transformation\u00a0\u00bb gagne aujourd\u2019hui en importance\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/03\/INP-Blog-FacilitationDeTransformation_IAF.jpg?fit=600%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/03\/INP-Blog-FacilitationDeTransformation_IAF.jpg?fit=600%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/03\/INP-Blog-FacilitationDeTransformation_IAF.jpg?fit=600%2C600&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":6793,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2025\/10\/07\/pourquoi-et-comment-developper-des-capacites-collectives-durables\/","url_meta":{"origin":1372,"position":1},"title":"Les capacit\u00e9s collectives\u00a0durables, nouvel enjeu strat\u00e9gique pour l&rsquo;entreprise","author":"In Principo","date":"7 octobre 2025","format":false,"excerpt":"Pourquoi et comment d\u00e9velopper des capacit\u00e9s collectives durables ? C'est pr\u00e9cis\u00e9ment cette question que, Vendredi 3 octobre, Olivier R\u00e9aud a d\u00e9velopp\u00e9 dans le MasterLab de IAF France devant un panel de facilitateurs professionnels, membres de France Facilitation, la communaut\u00e9 de d\u00e9veloppement des Facilitateurs de IAF France. Quel est l'enjeu ?\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251008-Blog_Capacites-Collectives-Durables.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251008-Blog_Capacites-Collectives-Durables.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251008-Blog_Capacites-Collectives-Durables.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251008-Blog_Capacites-Collectives-Durables.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/10\/251008-Blog_Capacites-Collectives-Durables.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7702,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2026\/04\/06\/olivier-reaud-et-stephane-demarquette-presentent-hybridvibes-a-ingenieurs-et-scientifiques-de-france\/","url_meta":{"origin":1372,"position":2},"title":"Olivier R\u00e9aud et St\u00e9phane Demarquette pr\u00e9sentent HybridVibes \u00e0 Ing\u00e9nieurs et Scientifiques de France","author":"Olivier Reaud","date":"6 avril 2026","format":false,"excerpt":"HybridVibes, associant intelligence collective et intelligence artificielle en une m\u00eame d\u00e9marche, est un v\u00e9ritable game changer dans l\u2019accompagnement de la transformation des organisations. Pour en parler ouvertement, Christophe Dubois Damien, Pr\u00e9sident Comit\u00e9 \u00e9conomie Ing\u00e9nieurs Et Scientifiques de France (IESF) invite Olivier R\u00e9aud et St\u00e9phane Demarquette \u00e0 pr\u00e9senter HybridVibes le 21\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/04\/260408-InPrincipo-IESF-CartoucheCarreV2.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/04\/260408-InPrincipo-IESF-CartoucheCarreV2.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/04\/260408-InPrincipo-IESF-CartoucheCarreV2.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/04\/260408-InPrincipo-IESF-CartoucheCarreV2.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2026\/04\/260408-InPrincipo-IESF-CartoucheCarreV2.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2024\/06\/12\/retrouvez-in-principo-dans-le-magazine-de-landrh\/","url_meta":{"origin":1372,"position":3},"title":"Retrouvez In Principo dans le Magazine de l\u2019ANDRH","author":"In Principo","date":"12 juin 2024","format":false,"excerpt":"Le Magazine de l\u2019ANDRH \u2013 le mensuel de l\u2019Association Nationale des DRH \u2013 consacre 10 pages dans son num\u00e9ro de juin \u00e0 la facilitation comme pratique montante et transformante du management dans un contexte de transitions chahut\u00e9es par l\u2019actualit\u00e9. Le dossier de 10 pages d\u00e9marre par une interview double page\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/06\/INP-couvANDRH-600x600-1-scaled.jpg?fit=1200%2C1195&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/06\/INP-couvANDRH-600x600-1-scaled.jpg?fit=1200%2C1195&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/06\/INP-couvANDRH-600x600-1-scaled.jpg?fit=1200%2C1195&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/06\/INP-couvANDRH-600x600-1-scaled.jpg?fit=1200%2C1195&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/06\/INP-couvANDRH-600x600-1-scaled.jpg?fit=1200%2C1195&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1368,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2024\/01\/19\/comment-se-transformer-dans-les-annees-turbulences\/","url_meta":{"origin":1372,"position":4},"title":"Comment se transformer dans les \u00ab\u00a0Ann\u00e9es Turbulences\u00a0\u00bb\u00a0?","author":"In Principo","date":"19 janvier 2024","format":false,"excerpt":"Apr\u00e8s la crise, qu\u2019est-ce qui se profile\u00a0? La transition comme cap mobilisateur de la soci\u00e9t\u00e9 - souhait\u00e9e et redout\u00e9e - a laiss\u00e9 sa place \u00e0 une totale incertitude. M\u00eame la notion de \u00ab\u00a0brouillard de l\u2019incertitude\u00a0\u00bb ne parait plus \u00eatre pertinente. Crises, atonies, brefs moments d\u2019enthousiasmes, se succ\u00e8dent\u00a0: bienvenue dans les\u2026","rel":"","context":"Dans &quot;FORMATIONS&quot;","block_context":{"text":"FORMATIONS","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/formations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/01\/INP-CartoucheBlog-AnneesTurbulences5.jpg?fit=600%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/01\/INP-CartoucheBlog-AnneesTurbulences5.jpg?fit=600%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2024\/01\/INP-CartoucheBlog-AnneesTurbulences5.jpg?fit=600%2C600&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":6574,"url":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/2025\/09\/05\/in-principo-paris-et-friends-montreal-engagent-un-partenariat-puissant\/","url_meta":{"origin":1372,"position":5},"title":"In Principo (Paris) et &amp;Friends (Montr\u00e9al) engagent un partenariat innovant sur l&rsquo;adoption de l&rsquo;IA","author":"In Principo","date":"5 septembre 2025","format":false,"excerpt":"C'est avec un grand plaisir que les \u00e9quipes In Principo et &Friends vous annoncent proposer ensemble une nouvelle g\u00e9n\u00e9ration d'accompagnements et de formations pour r\u00e9pondre aux d\u00e9fis strat\u00e9giques, humains et op\u00e9rationnels des organisations d'aujourd'hui : IA comme opportunit\u00e9 de d\u00e9veloppement collectif, \u00e9conomie r\u00e9inventive, \u00e9cosyst\u00e8mes r\u00e9g\u00e9n\u00e9ratifs. Objectif : l'int\u00e9gration du Design\u2026","rel":"","context":"Dans &quot;ACTU&quot;","block_context":{"text":"ACTU","link":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/category\/actu\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/09\/Cartouche-Partenariat-In-Principo-et-FriendsV8.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/09\/Cartouche-Partenariat-In-Principo-et-FriendsV8.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/09\/Cartouche-Partenariat-In-Principo-et-FriendsV8.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/09\/Cartouche-Partenariat-In-Principo-et-FriendsV8.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/inprincipo2024.inprincipo.com\/wp-content\/uploads\/2025\/09\/Cartouche-Partenariat-In-Principo-et-FriendsV8.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts\/1372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1372"}],"version-history":[{"count":1,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts\/1372\/revisions"}],"predecessor-version":[{"id":1374,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/posts\/1372\/revisions\/1374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/media\/3545"}],"wp:attachment":[{"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inprincipo2024.inprincipo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}